{"id":45336,"date":"2026-08-31T09:40:05","date_gmt":"2026-08-31T09:40:05","guid":{"rendered":"https:\/\/minitalienproperty.com\/it_it\/properties\/porzione-di-villetta-trifamiliare-al-confine-con-la-toscana\/"},"modified":"2026-08-31T09:40:05","modified_gmt":"2026-08-31T09:40:05","slug":"porzione-di-villetta-trifamiliare-al-confine-con-la-toscana","status":"publish","type":"wdk-listing","link":"https:\/\/minitalienproperty.com\/fi\/properties\/porzione-di-villetta-trifamiliare-al-confine-con-la-toscana\/","title":{"rendered":"Porzione di villetta trifamiliare al confine con la Toscana"},"content":{"rendered":"<p>Porzione capotesta di trifamiliare di circa 80 mq + garage di mq 60 con bagno, libera su tre lati in ottime condizioni. La casa \u00e8\u00a0 al piano terra con giardino perimetrale di circa 200 mq ed \u00e8 composta da spazioso soggiorno con camino, cucina abitabile, camera matrimoniale , cameretta e bagno. Riscaldamento autonomo. Ottima posizione! Lago di Bolsena 15 km; Terme di Saturnia 25 km; Mare 30 km. Siti archeologici nelle vicinanze. Aeroporto Roma Fiumicino circa 100 km<\/p>","protected":false},"excerpt":{"rendered":"<p>Porzione capotesta di trifamiliare di circa 80 mq + garage di mq 60 con bagno, libera su tre lati in ottime condizioni. La casa \u00e8\u00a0 al piano terra con giardino perimetrale di circa 200 mq ed \u00e8 composta da spazioso soggiorno con camino, cucina abitabile, camera matrimoniale , cameretta e bagno. Riscaldamento autonomo. Ottima posizione! [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"class_list":["post-45336","wdk-listing","type-wdk-listing","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Porzione di villetta trifamiliare al confine con la Toscana - MinItalien Property<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/minitalienproperty.com\/fi\/properties\/porzione-di-villetta-trifamiliare-al-confine-con-la-toscana\/\" \/>\n<meta property=\"og:locale\" content=\"fi_FI\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Porzione di villetta trifamiliare al confine con la Toscana - MinItalien Property\" \/>\n<meta property=\"og:description\" content=\"Porzione capotesta di trifamiliare di circa 80 mq + garage di mq 60 con bagno, libera su tre lati in ottime condizioni. La casa \u00e8\u00a0 al piano terra con giardino perimetrale di circa 200 mq ed \u00e8 composta da spazioso soggiorno con camino, cucina abitabile, camera matrimoniale , cameretta e bagno. Riscaldamento autonomo. Ottima posizione! [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/minitalienproperty.com\/fi\/properties\/porzione-di-villetta-trifamiliare-al-confine-con-la-toscana\/\" \/>\n<meta property=\"og:site_name\" content=\"MinItalien Property\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/minitalienproperty.com\/properties\/porzione-di-villetta-trifamiliare-al-confine-con-la-toscana\/\",\"url\":\"https:\/\/minitalienproperty.com\/properties\/porzione-di-villetta-trifamiliare-al-confine-con-la-toscana\/\",\"name\":\"Porzione di villetta trifamiliare al confine con la Toscana - MinItalien Property\",\"isPartOf\":{\"@id\":\"https:\/\/minitalienproperty.com\/#website\"},\"datePublished\":\"2026-08-31T09:40:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/minitalienproperty.com\/properties\/porzione-di-villetta-trifamiliare-al-confine-con-la-toscana\/#breadcrumb\"},\"inLanguage\":\"fi\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/minitalienproperty.com\/properties\/porzione-di-villetta-trifamiliare-al-confine-con-la-toscana\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/minitalienproperty.com\/properties\/porzione-di-villetta-trifamiliare-al-confine-con-la-toscana\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/minitalienproperty.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Porzione di villetta trifamiliare al confine con la Toscana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/minitalienproperty.com\/#website\",\"url\":\"https:\/\/minitalienproperty.com\/\",\"name\":\"MinItalien Property\",\"description\":\"Real Estate Marketplace between Italy and Scandinavia\",\"publisher\":{\"@id\":\"https:\/\/minitalienproperty.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/minitalienproperty.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fi\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/minitalienproperty.com\/#organization\",\"name\":\"MinItalien Property\",\"url\":\"https:\/\/minitalienproperty.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fi\",\"@id\":\"https:\/\/minitalienproperty.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/minitalienproperty.com\/wp-content\/uploads\/2022\/12\/200x200-Formato-senza-sottotitolo.png\",\"contentUrl\":\"https:\/\/minitalienproperty.com\/wp-content\/uploads\/2022\/12\/200x200-Formato-senza-sottotitolo.png\",\"width\":200,\"height\":104,\"caption\":\"MinItalien Property\"},\"image\":{\"@id\":\"https:\/\/minitalienproperty.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Porzione di villetta trifamiliare al confine con la Toscana - MinItalien Property","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/minitalienproperty.com\/fi\/properties\/porzione-di-villetta-trifamiliare-al-confine-con-la-toscana\/","og_locale":"fi_FI","og_type":"article","og_title":"Porzione di villetta trifamiliare al confine con la Toscana - MinItalien Property","og_description":"Porzione capotesta di trifamiliare di circa 80 mq + garage di mq 60 con bagno, libera su tre lati in ottime condizioni. La casa \u00e8\u00a0 al piano terra con giardino perimetrale di circa 200 mq ed \u00e8 composta da spazioso soggiorno con camino, cucina abitabile, camera matrimoniale , cameretta e bagno. Riscaldamento autonomo. Ottima posizione! [&hellip;]","og_url":"https:\/\/minitalienproperty.com\/fi\/properties\/porzione-di-villetta-trifamiliare-al-confine-con-la-toscana\/","og_site_name":"MinItalien Property","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/minitalienproperty.com\/properties\/porzione-di-villetta-trifamiliare-al-confine-con-la-toscana\/","url":"https:\/\/minitalienproperty.com\/properties\/porzione-di-villetta-trifamiliare-al-confine-con-la-toscana\/","name":"Porzione di villetta trifamiliare al confine con la Toscana - MinItalien Property","isPartOf":{"@id":"https:\/\/minitalienproperty.com\/#website"},"datePublished":"2026-08-31T09:40:05+00:00","breadcrumb":{"@id":"https:\/\/minitalienproperty.com\/properties\/porzione-di-villetta-trifamiliare-al-confine-con-la-toscana\/#breadcrumb"},"inLanguage":"fi","potentialAction":[{"@type":"ReadAction","target":["https:\/\/minitalienproperty.com\/properties\/porzione-di-villetta-trifamiliare-al-confine-con-la-toscana\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/minitalienproperty.com\/properties\/porzione-di-villetta-trifamiliare-al-confine-con-la-toscana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/minitalienproperty.com\/en\/"},{"@type":"ListItem","position":2,"name":"Porzione di villetta trifamiliare al confine con la Toscana"}]},{"@type":"WebSite","@id":"https:\/\/minitalienproperty.com\/#website","url":"https:\/\/minitalienproperty.com\/","name":"MinItalien Property","description":"Real Estate Marketplace between Italy and Scandinavia","publisher":{"@id":"https:\/\/minitalienproperty.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/minitalienproperty.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fi"},{"@type":"Organization","@id":"https:\/\/minitalienproperty.com\/#organization","name":"MinItalien Property","url":"https:\/\/minitalienproperty.com\/","logo":{"@type":"ImageObject","inLanguage":"fi","@id":"https:\/\/minitalienproperty.com\/#\/schema\/logo\/image\/","url":"https:\/\/minitalienproperty.com\/wp-content\/uploads\/2022\/12\/200x200-Formato-senza-sottotitolo.png","contentUrl":"https:\/\/minitalienproperty.com\/wp-content\/uploads\/2022\/12\/200x200-Formato-senza-sottotitolo.png","width":200,"height":104,"caption":"MinItalien Property"},"image":{"@id":"https:\/\/minitalienproperty.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/minitalienproperty.com\/fi\/wp-json\/wp\/v2\/wdk-listing\/45336","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/minitalienproperty.com\/fi\/wp-json\/wp\/v2\/wdk-listing"}],"about":[{"href":"https:\/\/minitalienproperty.com\/fi\/wp-json\/wp\/v2\/types\/wdk-listing"}],"author":[{"embeddable":true,"href":"https:\/\/minitalienproperty.com\/fi\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":2,"href":"https:\/\/minitalienproperty.com\/fi\/wp-json\/wp\/v2\/wdk-listing\/45336\/revisions"}],"predecessor-version":[{"id":45338,"href":"https:\/\/minitalienproperty.com\/fi\/wp-json\/wp\/v2\/wdk-listing\/45336\/revisions\/45338"}],"wp:attachment":[{"href":"https:\/\/minitalienproperty.com\/fi\/wp-json\/wp\/v2\/media?parent=45336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}